{"id":18838,"date":"2026-02-03T10:45:15","date_gmt":"2026-02-03T10:45:15","guid":{"rendered":"https:\/\/assetphysics.com\/?p=18838"},"modified":"2026-02-03T16:08:48","modified_gmt":"2026-02-03T16:08:48","slug":"deka-immobilien-verkauft-edison-hoefe-in-berlin","status":"publish","type":"post","link":"https:\/\/assetphysics.com\/de\/deka-immobilien-verkauft-edison-hoefe-in-berlin\/","title":{"rendered":"Deka Immobilien verkauft Edison H\u00f6fe in Berlin"},"content":{"rendered":"\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"x_MsoNormal\"><span data-olk-copy-source=\"MessageBody\">Die Deka Immobilien hat das B\u00fcro- und Gesch\u00e4ftsensemble Edison H\u00f6fe in Berlin-Mitte ver\u00e4u\u00dfert. K\u00e4ufer ist ein institutioneller Investor. Das Objekt stammt aus dem Portfolio des Offenen Immobilienfonds WestInvest ImmoValue, der sich ausschlie\u00dflich an institutionelle Investoren richtet. \u00dcber den Kaufpreis wurde Stillschweigen vereinbart.<\/span><\/p>\n<p class=\"x_MsoNormal\">Der Komplex in der Invalidenstra\u00dfe 116-119\/Schlegelstra\u00dfe 26, 26A-C besteht aus insgesamt acht B\u00fcro- und Gesch\u00e4ftsgeb\u00e4uden mit einer vermietbaren Fl\u00e4che von 27.700 qm und 129 Parkpl\u00e4tzen. Er setzt sich aus dem 2012 fertig gestellten Neubau Torhaus und dem ehemaligen Fabrikgeb\u00e4ude der AEG zusammen, das 1880 errichtet und zwischen 2002 bis 2004 kernsaniert sowie aufgestockt wurde.<\/p>\n<p class=\"x_MsoNormal\">Mit diesem Verkauf nutzt das Fondsmanagement des WestInvest ImmoValue eine Marktchance, um die Liegenschaft nach fast 13 Jahren deutlich \u00fcber dem Ankaufspreis zu ver\u00e4u\u00dfern.<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Deka Immobilien hat die Edison H\u00f6fe in Berlin-Mitte an einen institutionellen Investor verkauft. \u00dcber den Kaufpreis wurde Stillschweigen vereinbart. Der Komplex umfasst acht B\u00fcro- und Gesch\u00e4ftsgeb\u00e4ude.<\/p>\n","protected":false},"author":211,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_co_authors":[],"footnotes":""},"categories":[23,10],"tags":[],"type_content":[170],"class_list":["post-18838","post","type-post","status-publish","format-standard","hentry","category-deals","category-real-estate","type_content-news"],"acf":{"homepage_featured_article":false},"_links":{"self":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/18838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/users\/211"}],"replies":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/comments?post=18838"}],"version-history":[{"count":2,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/18838\/revisions"}],"predecessor-version":[{"id":18840,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/18838\/revisions\/18840"}],"wp:attachment":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/media?parent=18838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/categories?post=18838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/tags?post=18838"},{"taxonomy":"type_content","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/type_content?post=18838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}