{"id":31031,"date":"2026-05-11T06:43:57","date_gmt":"2026-05-11T06:43:57","guid":{"rendered":"https:\/\/assetphysics.com\/?p=31031"},"modified":"2026-05-11T06:43:57","modified_gmt":"2026-05-11T06:43:57","slug":"18-nai-apollo-soccer-cup-2026-fussball-networking-und-engagement-fuer-kinder-im-krankenhaus","status":"publish","type":"post","link":"https:\/\/assetphysics.com\/de\/18-nai-apollo-soccer-cup-2026-fussball-networking-und-engagement-fuer-kinder-im-krankenhaus\/","title":{"rendered":"18. NAI apollo Soccer Cup 2026: Fu\u00dfball, Networking und Engagement f\u00fcr Kinder im Krankenhaus"},"content":{"rendered":"\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Am 8. Mai 2026 veranstaltete NAI apollo den 18. Soccer Cup im Sportleistungszentrum von Eintracht Frankfurt am Riederwald. Das traditionsreiche Branchenturnier brachte erneut Unternehmen der Immobilien- und Beratungsbranche zusammen und verband sportlichen Wettbewerb mit pers\u00f6nlichem Austausch und gesellschaftlichem Engagement. Schirmherr der Veranstaltung war wie immer Dragoslav Stepanovic \u2013 Fu\u00dfball- und Trainerlegende von Eintracht Frankfurt sowie langj\u00e4hriger Schirmherr der Veranstaltung. Seine Pr\u00e4senz verlieh dem Turnier auch in diesem Jahr wieder eine besondere Note.&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Insgesamt 24 Unternehmen nahmen am Turnier teil und sorgten bei fr\u00fchlingshaftem Sonnenschein f\u00fcr spannende Partien, Fairplay und eine lebendige Turnieratmosph\u00e4re auf und neben dem Platz. Der Soccer Cup hat sich damit seit fast 20 Jahren als feste Gr\u00f6\u00dfe im Branchenkalender etabliert.&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>Finale &#038; Turniersieger<\/h3>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Nach einer packenden Gruppenphase und teilweise hochklassigen Spielen in der K.O.-Runde standen sich im Finale Realogis Immobilien Frankfurt GmbH und GONDER Facility Services GmbH gegen\u00fcber. In einem hart umk\u00e4mpften Spiel setzte sich Realogis verdient durch und sicherte sich damit den begehrten Pokal. Herzlichen Gl\u00fcckwunsch!&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>\u201eEs erf\u00fcllt uns mit gro\u00dfer Freude und Stolz, dass wir in diesem Jahr bereits den 18. NAI apollo Soccer Cup austragen durften. Dieses Turnier steht seit Jahren f\u00fcr weit mehr als sportlichen Wettbewerb \u2013 es steht f\u00fcr Zusammenhalt, Fairplay und gesellschaftliche Verantwortung. In diesem Jahr freuen wir uns besonders, das Aktionskomitee KIND IM KRANKENHAUS \u2013 AKIK Frankfurt \/ Rhein-Main e.V. unterst\u00fctzen zu k\u00f6nnen, das sich seit Jahrzehnten ehrenamtlich f\u00fcr Kinder und Jugendliche in Krankenh\u00e4usern einsetzt. Dass wir gemeinsam mit so vielen engagierten Unternehmen nicht nur gro\u00dfartigen Fu\u00dfball erleben, sondern auch einen bedeutenden Beitrag f\u00fcr diesen Verein leisten konnten, macht diesen Tag jedes Jahr aufs Neue zu etwas ganz Besonderem.&#8220;&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p><strong>\u2013 Marcel Crommen<\/strong>, Managing Partner, NAI apollo<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p><strong>Der Thekenpokal \u2013 die inoffizielle, aber nicht minder hei\u00df begehrte Auszeichnung des Abends<\/strong> \u2013 ging in diesem Jahr an <strong>Colliers<\/strong>. F\u00fcr beeindruckende Ausdauer, unersch\u00fctterliche Standfestigkeit am Glas und Leistungen, die man wohl nur abseits des Spielfelds wirklich perfektionieren kann. Eine Auszeichnung, die im Branchenged\u00e4chtnis bleibt \u2013 zumindest bis zum n\u00e4chsten Jahr. &nbsp;<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>Soziales Engagement: Spende f\u00fcr AKIK e.V.<\/h3>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Auch beim 18. NAI apollo Soccer Cup stand der soziale Gedanke im Mittelpunkt. Unterst\u00fctzt wurde das <strong>Aktionskomitee KIND IM KRANKENHAUS \u2013 AKIK Frankfurt \/ Rhein-Main e. V<\/strong>. Der gemeinn\u00fctzige Verein engagiert sich seit 1982 ehrenamtlich f\u00fcr das Wohlergehen von Kindern und Jugendlichen in Krankenh\u00e4usern sowie in pflegerischen und betreuenden Einrichtungen im Rhein-Main-Gebiet. Die ehrenamtlichen Mitglieder begleiten junge Patientinnen und Patienten w\u00e4hrend ihres Aufenthaltes, schenken Zeit, Zuwendung und Ablenkung und entlasten zugleich deren Familien.<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Dank der engagierten Teilnahme und Unterst\u00fctzung aller Beteiligten konnte eine Spendensumme von insgesamt <strong>9.200 Euro<\/strong> erzielt werden, die dem Verein AKIK e.V. zugutekommt.&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>\u201eWir sind dem NAI apollo Soccer Cup und allen beteiligten Unternehmen von Herzen dankbar f\u00fcr die gro\u00dfartige Unterst\u00fctzung. Jeder gespendete Euro kommt den Kindern und Jugendlichen zugute, die ihren Krankenhausaufenthalt oft als belastend und einsam erleben.&nbsp;Unsere ehrenamtlichen AKIK-Betreuerinnen und Betreuer unterst\u00fctzen hier auf vielf\u00e4ltige Weise.&nbsp;Dank des Engagements von NAI apollo und seinen Partnern k\u00f6nnen wir unsere ehrenamtliche Arbeit weiter ausbauen und noch mehr jungen Patientinnen und Patienten im Rhein-Main-Gebiet zur Seite stehen. Es ist wunderbar zu sehen, wie der Sport Menschen zusammenbringt \u2013 und dabei gleichzeitig etwas Sinnvolles bewirkt.\u201c&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p><strong>\u2013 <\/strong>Karin Schmidt , AKIK Frankfurt \/ Rhein-Main e.V.&nbsp;<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>Sponsoren und teilnehmende Unternehmen<\/h3>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Ein besonderer Dank gilt den Hauptsponsoren des 18. NAI apollo Soccer Cup: <strong>Autohaus Brass GmbH &#038; Co. KG, GONDER Facility Services GmbH, Jones Lang LaSalle SE.<\/strong><\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Dar\u00fcber hinaus wurde das Turnier unterst\u00fctzt von: Beos Swiss Life Asset Managers Deutschland GmbH, Berkers &#038; Cie. GmbH &#038; Co. KG, Colliers International, Westbridge, Funk Versicherungsmakler GmbH, Realogis Immobilien Frankfurt GmbH, von Poll Immobilien GmbH.<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Am 18. NAI apollo Soccer Cup 2026 nahmen folgende Unternehmen teil: aam2core Holding AG, aedifion GmbH, Autohaus Brass GmbH &#038; Co. KG, Berkers &#038; Cie. GmbH &#038; Co. KG, blackolive advisors GmbH, BNP Paribas Real Estate GmbH, Cushman &#038; Wakefield&nbsp; (UK) LLP, Colliers International, Designfunktion Rhein Main GmbH, EVC Rhein-Main GmbH, Frankfurter Sparkasse 1822, GONDER Facility Services GmbH, Gowling WLG (UK) LLP, Habona Invest GmbH, HIH Real Estate GmbH, Jones Lang LaSalle SE, N17 Projects GmbH, NAI apollo, Nuveen Asset Management Europe S\u00e0rl, Germany, Panattoni Germany Properties GmbH, Realogis Immobilien Frankfurt GmbH, Swiss Life \/ Beos, von Poll Immobilien GmbH, Westbridge.<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Dragoslav Stepanovic; Paola Fruttuoso, NAI apollo; Karin Schmidt,&nbsp;AKIK Frankfurt \/ Rhein-Main e.V.; Dr. Marcel Crommen, NAI apollo. Bildquelle: NAI apollo.<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\t<section class=\"snk-section snk-section_noPadding\">\n\t\t<div class=\"container container-xs\">\n\t\t\t<div class=\"snk-media snk-media_image\">\n\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/assetphysics.com\/wp-content\/uploads\/2026\/05\/vcsprasset_3698610_526280_aef16ba1-cc1e-4434-9db2-57e7abd68966_0.jpg\" alt=\"Gruppenfoto: Dragoslav Stepanovic, Paola Fruttuoso (NAI apollo), Karin Schmidt (AKIK Frankfurt \/ Rhein-Main e.V.) und Dr. Marcel Crommen (NAI apollo) bei der Scheck\u00fcbergabe auf dem Fu\u00dfballplatz.\" title=\"Gruppenbild NAI apollo Soccer Cup 2026 \u2013 Scheck\u00fcbergabe an AKIK e.V.\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1200px; --smush-placeholder-aspect-ratio: 1200\/1600;\" \/>\n\t\t\t\t\t\t<div class=\"snk-media-caption\">Dragoslav Stepanovic; Paola Fruttuoso, NAI apollo; Karin Schmidt, AKIK Frankfurt \/ Rhein-Main e.V.; Dr. Marcel Crommen, NAI apollo. Bildquelle: NAI apollo.<\/div>\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t<\/section>\n\t","protected":false},"excerpt":{"rendered":"<p>NAI apollo hat am 8. Mai 2026 den 18. Soccer Cup im Sportleistungszentrum von Eintracht Frankfurt ausgerichtet. Realogis Immobilien Frankfurt gewann das Finale gegen GONDER. Zudem kamen 9.200 Euro Spenden f\u00fcr AKIK Frankfurt\/Rhein-Main e.V. zusammen.<\/p>\n","protected":false},"author":217,"featured_media":31028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_co_authors":[],"footnotes":""},"categories":[875],"tags":[],"type_content":[170],"class_list":["post-31031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dynamics","type_content-news"],"acf":{"homepage_featured_article":false},"_links":{"self":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/31031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/users\/217"}],"replies":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/comments?post=31031"}],"version-history":[{"count":1,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/31031\/revisions"}],"predecessor-version":[{"id":31032,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/31031\/revisions\/31032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/media\/31028"}],"wp:attachment":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/media?parent=31031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/categories?post=31031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/tags?post=31031"},{"taxonomy":"type_content","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/type_content?post=31031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}