{"id":37670,"date":"2026-07-06T05:47:34","date_gmt":"2026-07-06T05:47:34","guid":{"rendered":"https:\/\/assetphysics.com\/?p=37670"},"modified":"2026-07-06T05:47:34","modified_gmt":"2026-07-06T05:47:34","slug":"bf-quartalsbarometer-q2-2026-stimmung-unter-den-immobilienfinanzierern-bricht-ein","status":"publish","type":"post","link":"https:\/\/assetphysics.com\/de\/bf-quartalsbarometer-q2-2026-stimmung-unter-den-immobilienfinanzierern-bricht-ein\/","title":{"rendered":"BF.Quartalsbarometer Q2 2026: Stimmung unter den Immobilienfinanzierern bricht ein"},"content":{"rendered":"\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Die Stimmung unter den gewerblichen Immobilienfinanzierern ist im zweiten Quartal 2026 deutlich schlechter geworden. Das zeigt das aktuelle BF.Quartalsbarometer, das die BF.direkt AG in Kooperation mit dem Handelsblatt Research Institute erstellt. Der Barometerwert fiel von -9,74 auf nun -25,97 Punkte. Ein solch negativer Wert signalisiert eine stark eingeschr\u00e4nkte Finanzierungsbereitschaft. Die Befragung fand vom 8. bis 16. Juni 2026 statt.<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Viele wesentliche Parameter haben sich der Befragung zufolge verschlimmert: Fast die H\u00e4lfte der Befragten (46,15 Prozent) gab an, dass sich die Finanzierungsbedingungen im Vergleich zum Vorquartal verschlechtert h\u00e4tten. Im Q1 lag dieser Wert noch bei 27,27 Prozent. Auch die Entwicklung des Neugesch\u00e4fts f\u00e4llt negativer aus. 23,08 Prozent berichteten im Q2 von einem abnehmenden Neugesch\u00e4ft (Q1: 0,0 Prozent). Ebenso zeigt die Entwicklung der Kreditvolumina nach unten: \u00dcber alle Institutsgr\u00f6\u00dfen hinweg manifestiert sich eine Zunahme kleinerer Kredite unter zehn Mio. Euro und eine Abnahme gr\u00f6\u00dferer Finanzierungen in der Spanne 50 bis 100 Mio. Euro und \u00fcber 100 Mio. Euro.\u00a0<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Verschiebungen gab es auch beim Zustandekommen von Kreditentscheidungen. 26,92 Prozent (+17,82 Prozentpunkte) der Befragten gaben an, Kreditentscheidungen seien gr\u00f6\u00dftenteils von der Risikoabteilung beeinflusst worden. Gr\u00f6\u00dftenteils vom Neugesch\u00e4ftsbereich beeinflusst waren hingegen \u00fcberhaupt keine Kreditentscheidungen (-7,69 Prozentpunkte). \u00a0<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Professor Dr. Steffen Sebastian, Inhaber des Lehrstuhls f\u00fcr Immobilienfinanzierung an der IREBS und wissenschaftlicher Berater des BF.Quartalsbarometers, sagt: \u201eDie Ergebnisse sind vor allem mit dem Irankrieg und seinen Folgen zu erkl\u00e4ren. Der Energiepreisschock wirkt inflationserh\u00f6hend, was wiederum die Angst vor steigenden Zinsen nach sich zieht. Dies trifft auf eine Branche, die sich seit dem starken Zinsanstieg 2022 ohnehin in einer fragilen Situation befindet.\u201c\u00a0<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Francesco Fedele, CEO der BF.direkt AG, erg\u00e4nzt: \u201eDie letzte Quartalsbarometerbefragung lief ganz zu Beginn des Irankonfliktes. Viele Finanzierer reagierten zun\u00e4chst gelassen. Diese Gelassenheit ist aber im Verlauf des Q2 verschwunden und hat zum Einbruch der Stimmung und damit des Barometers gef\u00fchrt.\u201c<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Dr. Sven Jung, Director Economic Analysis &#038; Financial Planning beim Handelsblatt Research Institute, kommentiert: \u201eZu den weiteren zentralen Ergebnissen der Befragung z\u00e4hlt, dass der Wettbewerb zwischen den Instituten um gute Finanzierungen eher abnimmt, wie 26,92 Prozent der Befragten angaben. Im ersten Quartal waren es noch 5,88 Prozent. Zugenommen hat hingegen die Quote der NPLs: Der Anteil der Befragten, der von einem Anstieg berichtete, wuchs von 18,18 auf 30,77 Prozent. Beide Teilergebnisse passen zu der negativen Entwicklung im zweiten Quartal.\u201c<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Fabio Carrozza, Chief Sales Officer der BF.direkt AG, kommentiert: \u201eDie Befunde des Quartalsbarometers decken sich mit unseren Beobachtungen in der Praxis: Wir sehen aktuell, dass viele Banken ihr Neugesch\u00e4ft deutlich selektiver steuern und parallel verst\u00e4rkt mit Problemkrediten im Bestand besch\u00e4ftigt sind. Beides bindet Ressourcen und reduziert die Bereitschaft, neue Finanzierungen einzugehen. Die sich daraus ergebenden M\u00f6glichkeiten nutzen Debt-Fonds, um Projekte zu finanzieren, die grunds\u00e4tzlich tragf\u00e4hig sind, aber nicht mehr in jedes Bankenraster passen.\u201c<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Weniger Bewegung gab es hingegen bei Loan-to-values (LTVs) bzw. Loan-to-Costs (LTCs) und Margen. Die Margen entwickelten sich je nach Nutzungsart uneinheitlich und reichen von 135,0 Basispunkten (Wohnen) bis zu 184,3 Basispunkten (Logistik) im Bestand und von 252,7 Basispunkten (Wohnen) bis 301,1 Basispunkten (B\u00fcro) bei Projektentwicklungen. Die LTVs (Bestand) lagen \u00fcber alle Nutzungsarten hinweg im Schnitt bei 64,2 Prozent und die LTCs (Projektentwicklung) bei 66,3 Prozent.<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>Zur Methodik<\/h3>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Das BF.Quartalsbarometer wird im Auftrag der BF.direkt AG, Spezialist f\u00fcr die Finanzierung von Real Assets, durch das Handelsblatt Research Institute erarbeitet. Wissenschaftlicher Berater des BF.Quartalsbarometers ist Prof. Dr. Steffen Sebastian, Inhaber des Lehrstuhls f\u00fcr Immobilienfinanzierung an der IREBS. Der Index bildet die Stimmung und das Gesch\u00e4ftsklima der Immobilienfinanzierer in Deutschland umfassend ab.<br \/>\nZur Ermittlung des BF.Quartalsbarometers werden viertelj\u00e4hrlich aktuell 38 Expertinnen und Experten befragt, die alle unmittelbar mit der Kreditvergabe an Immobilienunternehmen betraut sind. Das Panel besteht aus Vertretern unterschiedlicher Banken und alternativer Finanzierer.<br \/>\nDer Wert des BF.Quartalsbarometers setzt sich aus Aussagen zu folgenden Aspekten zusammen: Beurteilung der aktuellen Finanzierungsbedingungen, Entwicklung des Neugesch\u00e4fts, durchschnittliches Kreditvolumen der Einzelgesch\u00e4fte, tonangebende Abteilung bei den Kreditentscheidungen, Entwicklung der NPL-Quote, Bedeutung alternativer Finanzierungsm\u00f6glichkeiten und Entwicklung der Wettbewerbssituation.<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n\n\t<section class=\"snk-section snk-section_noPadding\">\n\t\t<div class=\"container container-xs\">\n\t\t\t<div class=\"snk-media snk-media_image\">\n\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/assetphysics.com\/wp-content\/uploads\/2026\/07\/bf.quartalsbarometer_copyright_bf.direkt.jpg\" alt=\"Grafik zeigt den Indexwert des BF.Quartalsbarometers f\u00fcr Q2 2026 mit -25,97 Punkten und Q1 2026 mit -9,74 Punkten.\" title=\"BF.Quartalsbarometer Q2 2026: Indexentwicklung\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1306px; --smush-placeholder-aspect-ratio: 1306\/541;\" \/>\n\t\t\t\t\t\t<div class=\"snk-media-caption\">Der Indexwert des BF.Quartalsbarometers sinkt im zweiten Quartal 2026 auf -25,97 Punkte. Bildquelle: BF.direkt AG<\/div>\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t<\/section>\n\t\n\n\n\t<section class=\"snk-section snk-section_noPadding\">\n\t\t<div class=\"container container-xs\">\n\t\t\t<div class=\"snk-media snk-media_image\">\n\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/assetphysics.com\/wp-content\/uploads\/2026\/07\/l_francesco_fedele_r_prof_steffen_sebastian_copyright_bf_direkt_ag.jpeg\" alt=\"Francesco Fedele und Prof. Steffen Sebastian, BF.direkt AG, Portraitfoto\" title=\"Francesco Fedele und Prof. Steffen Sebastian von BF.direkt AG\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1181px; --smush-placeholder-aspect-ratio: 1181\/787;\" \/>\n\t\t\t\t\t\t<div class=\"snk-media-caption\">Francesco Fedele (links) und Prof. Steffen Sebastian (rechts), Experten der BF.direkt AG. Bildquelle: BF.direkt AG<\/div>\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t<\/section>\n\t","protected":false},"excerpt":{"rendered":"<p>Das BF.Quartalsbarometer der BF.direkt AG fiel im Q2 2026 von -9,74 auf -25,97 Punkte und signalisiert stark eingeschr\u00e4nkte Finanzierungsbereitschaft. Ursachen sind u. a. der Irankrieg mit Inflations- und Zins\u00e4ngsten. Bedingungen, Neugesch\u00e4ft und Volumina verschlechtern sich.<\/p>\n","protected":false},"author":191,"featured_media":37664,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_co_authors":[],"footnotes":""},"categories":[24,10],"tags":[],"type_content":[34,21],"class_list":["post-37670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-markets","category-real-estate","type_content-quarterly","type_content-report"],"acf":{"homepage_featured_article":false},"_links":{"self":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/37670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/comments?post=37670"}],"version-history":[{"count":2,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/37670\/revisions"}],"predecessor-version":[{"id":37693,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/37670\/revisions\/37693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/media\/37664"}],"wp:attachment":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/media?parent=37670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/categories?post=37670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/tags?post=37670"},{"taxonomy":"type_content","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/type_content?post=37670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}