{"id":8390,"date":"2025-08-04T09:54:18","date_gmt":"2025-08-04T09:54:18","guid":{"rendered":"https:\/\/assetphysics.com\/?p=8390"},"modified":"2025-08-04T09:54:18","modified_gmt":"2025-08-04T09:54:18","slug":"deutsche-investment-erwirbt-wohn-und-geschaeftshausportfolio-in-leipzig","status":"publish","type":"post","link":"https:\/\/assetphysics.com\/de\/deutsche-investment-erwirbt-wohn-und-geschaeftshausportfolio-in-leipzig\/","title":{"rendered":"Deutsche Investment erwirbt Wohn- und Gesch\u00e4ftshausportfolio in Leipzig"},"content":{"rendered":"\n\t<section class=\"snk-section snk-section_xs\" >\n\t\t<div class=\"container container-xs\">\n\n\t\t\t\n\n\t\t\t\n\t\t\t\t<div class=\"row snk-textColumns\">\n\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"col col-12 snk-textColumn\">\n\t\t\t\t\t\t\t<div class=\"snk-textBlock\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3>Ankauf eines Wohn- und Gesch\u00e4ftshausportfolios in Leipzig mit 97 Wohneinheiten und 12 Gewerbeeinheiten.<\/h3>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>Die Deutsche Investment hat im Rahmen eines Individualmandats ein attraktives Wohn- und Gesch\u00e4ftsportfolio off-market erworben. Die sieben Liegenschaften umfassen insgesamt 97 Wohneinheiten, 12 Gewerbeeinheiten und 12 Stellpl\u00e4tze auf einer Gesamtmietfl\u00e4che von rund 10.800 m\u00b2. Das Gesamtinvestitionssvolumen betr\u00e4gt rd. 21 Mio. Euro.<\/p>\n<p>Die Objekte befinden sich in gefragten Stadtteillagen, unter anderem in der Karl-Liebknecht-Stra\u00dfe und Johannesallee, die durch ihre lebendige Infrastruktur und exzellente \u00d6PNV-Anbindung \u00fcberzeugen. Rund 85 % der Mietfl\u00e4che entfallen auf Wohnraum, w\u00e4hrend 15 % gewerblich genutzt werden. Ein Gro\u00dfteil der Wohnfl\u00e4chen liegt \u00fcber 60 m\u00b2, was besonders f\u00fcr Paare und Familien attraktiv ist, einer Zielgruppe, die in Leipzig von der Wohnungsknappheit besonders betroffen ist. Dies spiegelt sich auch in der hohen Mieterbindung wider: 54 % der Mietvertr\u00e4ge bestehen seit mehr als zehn Jahren, was auf ein stabiles und zufriedenes Mieterklientel hindeutet.<\/p>\n<p>Die repr\u00e4sentativen Liegenschaften stammen \u00fcberwiegend aus der Gr\u00fcnderzeit. Sechs der sieben Objekte wurden zwischen 1875 und 1912 errichtet, erg\u00e4nzt durch ein Geb\u00e4ude aus dem Jahr 1927. Die Mikrolagen zeichnen sich durch eine sehr gute Infrastruktur und exzellente Anbindung an den \u00f6ffentlichen Nahverkehr aus.<\/p>\n<p>Der Gewerbebereich unterteilt sich in B\u00fcro- (37 %) und Gastronomienutzungen (43 %). Besonders die Gastronomiefl\u00e4chen, etwa in der Johannisallee oder der Karl-Liebknecht-Stra\u00dfe, zeichnen sich durch hohe Sichtbarkeit und einer guten Frequenz aus. Weitere 20 % der Gewerbemieteinnahmen entfallen auf Laden- und Praxisfl\u00e4chen.<\/p>\n<p>Bei der Transaktion wurde die Deutsche Investment in rechtlichen Belangen von VESTHAUS Rechtsanw\u00e4lte und in Bezug auf das technische Gutachten von CBRE Berlin beraten. W\u00fcest Partner fungierte als Bewerter.<\/p>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"snk-buttons snk-buttons_bigGap\">\n\t\t\t\t\t\t\t\t\t<a class=\"snk-btn-primary\" href=\"https:\/\/www.deutsche-investment.com\/aktuelles\/deutsche-investment-erwirbt-wohn-und-geschaeftsportfolio-in-leipzig\" target=\"_blank\" rel=\"noopener\"><span>Pressemitteilung bei Deutsche Investment lesen<\/span><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/section>\n\n\n<section class=\"snk-section snk-section_xs\">\n\t<div class=\"container container-xs snk-testimonial-container\">\t<div class=\"row\">\n\t\t<div class=\"snk-testimonial\">\n\t\t\t<div class=\"snk-testimonial-inner\">\n\t\t\t\t<div class=\"snk-testimonial-content-wrapper\">\n\t\t\t\t\t<div class=\"snk-testimonial-content\">\n\t\t\t\t\t\t<figure class=\"snk-testimonial-quote\">\n\t\t\t\t\t\t\t<blockquote><p>Mit dem Erwerb des Leipziger Portfolios sichern wir uns ein substanzstarkes Investment in einer wachsenden Metropolregion. Die Kombination aus stabiler Mieterstruktur, attraktiven Wohnungsgr\u00f6\u00dfen und gefragten Mikrolagen bietet langfristiges Potenzial \u2013 sowohl in der Bestandsbewirtschaftung als auch in der Wertentwicklung.\u201c<\/p><\/blockquote>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"snk-testimonial-caption snk-text_sm\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-testimonial-name\">Sascha Basic<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"snk-testimonial-title\">Vorstand Deutsche Investment Kapitalverwaltung AG.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\t\n\t\t<\/div>\n\t<\/div>\n<\/section>\n\t\n\n\n\t<section class=\"snk-section snk-section_noPadding\">\n\t\t<div class=\"container container-xs\">\n\t\t\t<div class=\"snk-media snk-media_image\">\n\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/assetphysics.com\/wp-content\/uploads\/2025\/08\/Paul-Gruner-Strasse_3_Leipzig-e1754300461823.jpg\" alt=\"Foto: Deutsche Investment\" title=\"Paul-Gruner-Stra\u00dfe_3_Leipzig\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1030px; --smush-placeholder-aspect-ratio: 1030\/858;\" \/>\n\t\t\t\t\t\t<div class=\"snk-media-caption\">Foto: Deutsche Investment<\/div>\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t<\/section>\n\t\n\n\n\t<section class=\"snk-section snk-section_noPadding\">\n\t\t<div class=\"container container-xs\">\n\t\t\t<div class=\"snk-media snk-media_image\">\n\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/assetphysics.com\/wp-content\/uploads\/2025\/08\/20250203_121837037_iOS-scaled-e1754300619505.jpg\" alt=\"\" title=\"20250203_121837037_iOS\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 1370px; --smush-placeholder-aspect-ratio: 1370\/1647;\" \/>\n\t\t\t\t\t\t<div class=\"snk-media-caption\">Foto: Deutsche Investment<\/div>\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t<\/section>\n\t\n\n\n\t<section class=\"snk-section snk-section_noPadding\">\n\t\t<div class=\"container container-xs\">\n\t\t\t<div class=\"snk-media snk-media_image\">\n\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/assetphysics.com\/wp-content\/uploads\/2025\/08\/20250203_133658056_iOS-scaled-e1754300851674.jpg\" alt=\"\" title=\"20250203_133658056_iOS\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 2313px; --smush-placeholder-aspect-ratio: 2313\/1673;\" \/>\n\t\t\t\t\t\t<div class=\"snk-media-caption\">Foto: Deutsche Investment<\/div>\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t<\/section>\n\t","protected":false},"excerpt":{"rendered":"<p>Die Deutsche Investment hat im Rahmen eines Individualmandats ein attraktives Wohn- und Gesch\u00e4ftsportfolio off-market erworben. Die sieben Liegenschaften umfassen insgesamt 97 Wohneinheiten, 12 Gewerbeeinheiten und 12 Stellpl\u00e4tze auf einer Gesamtmietfl\u00e4che von rund 10.800 m\u00b2. Das Gesamtinvestitionssvolumen betr\u00e4gt rd. 21 Mio. Euro.<\/p>\n","protected":false},"author":134,"featured_media":8393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_co_authors":[],"footnotes":""},"categories":[23,10],"tags":[194,633,193,146,553],"type_content":[170],"class_list":["post-8390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deals","category-real-estate","tag-immobilien","tag-investment-de","tag-real-estate-2","tag-wohnen","tag-wohnen-deutschland-de","type_content-news"],"acf":{"homepage_featured_article":false},"_links":{"self":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/8390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/users\/134"}],"replies":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/comments?post=8390"}],"version-history":[{"count":6,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/8390\/revisions"}],"predecessor-version":[{"id":8404,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/posts\/8390\/revisions\/8404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/media\/8393"}],"wp:attachment":[{"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/media?parent=8390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/categories?post=8390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/tags?post=8390"},{"taxonomy":"type_content","embeddable":true,"href":"https:\/\/assetphysics.com\/de\/wp-json\/wp\/v2\/type_content?post=8390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}